{"id":65,"date":"2014-02-11T13:07:34","date_gmt":"2014-02-11T13:07:34","guid":{"rendered":"http:\/\/www.encontracamacari.com.br\/noticias\/?p=65"},"modified":"2019-04-29T20:48:25","modified_gmt":"2019-04-29T20:48:25","slug":"saude-em-camacari-upa-sera-inaugurada-em-marco","status":"publish","type":"post","link":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/","title":{"rendered":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o"},"content":{"rendered":"<div class=\"2410bb7248a64bb1f71103797e0f239b\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na UPA da Gleba A\u201d, disse.<\/p>\n<p>Segundo o secret\u00e1rio da Sa\u00fade, Vital Sampaio, as interven\u00e7\u00f5es na unidade de sa\u00fade est\u00e3o em fase de conclus\u00e3o. \u201cEm seguida, iremos instalar os aparelhos e realizar os devidos testes, para ent\u00e3o inaugurarmos a unidade de sa\u00fade\u201d, revelou.<\/p>\n<p>Com capacidade para atender cerca de 150 mil pessoas, a\u00a0UPA da Gleba A funcionar\u00e1 com servi\u00e7o de atendimento de urg\u00eancia e contar\u00e1 com 10 leitos para atender a popula\u00e7\u00e3o com atendimentos cl\u00ednico, pedi\u00e1trico, odontol\u00f3gico e ginecol\u00f3gico, 24 horas por dia. A unidade de sa\u00fade ter\u00e1 quatros m\u00e9dicos plantonistas, dois enfermeiros, oito t\u00e9cnicos de enfermagens, al\u00e9m de uma equipe de apoio.<\/p><div class=\"2410bb7248a64bb1f71103797e0f239b\" data-index=\"2\" style=\"float: none; margin:0px;\">\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"2899217073\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\r\n<\/br><\/br>\n<\/div>\n\n<p>Morador do bairro Gravat\u00e1, vizinho a UPA, o vereador Jackson Josu\u00e9 (SD), declarou que a unidade de sa\u00fade \u00e9 uma conquista da popula\u00e7\u00e3o. \u201cEste \u00e9 um sonho que est\u00e1 se realizando, n\u00e3o s\u00f3 para comunidade, mas para todo o Munic\u00edpio\u201d, ressaltou.<\/p>\n<p>A visita do prefeito Ademar Delgado foi acompanhada pelos secret\u00e1rios de Governo, Sergio Paiva, de Rela\u00e7\u00f5es Institucionais, Anderson Santos, da Inclus\u00e3o e Cidadania, Fabio Pereira, dos Servi\u00e7os P\u00fablicos, Z\u00e9 de El\u00edsio, e do Esporte e Lazer, Marco Antonio. Marcaram presen\u00e7a tamb\u00e9m o ouvidor do Munic\u00edpio, Tem\u00edstocles Matos, e o vereador Oziel Ara\u00fajo (PT).<\/p>\n<div class=\"2410bb7248a64bb1f71103797e0f239b\" data-index=\"3\" style=\"float: none; margin:0px;\">\n<\/br><\/br>\r\n\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-layout-key=\"-63+do+n-1s+9e\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"6838462089\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na UPA da Gleba A\u201d, disse. Segundo o secret\u00e1rio da Sa\u00fade, Vital Sampaio, as interven\u00e7\u00f5es na unidade de sa\u00fade est\u00e3o em fase de conclus\u00e3o. \u201cEm seguida, iremos instalar os aparelhos e realizar os devidos testes, para ent\u00e3o inaugurarmos a unidade de sa\u00fade\u201d, revelou. Com capacidade para <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-noticias-em-camacari"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Cama\u00e7ari\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Cama\u00e7ari - Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Cama\u00e7ari e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-02-11T13:07:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T20:48:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#blogposting\",\"name\":\"Sa\\u00fade em Cama\\u00e7ari: UPA ser\\u00e1 inaugurada em mar\\u00e7o - Encontra Cama\\u00e7ari\",\"headline\":\"Sa\\u00fade em Cama\\u00e7ari: UPA ser\\u00e1 inaugurada em mar\\u00e7o\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/author\\\/ecamacari\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2014-02-11T13:07:34+00:00\",\"dateModified\":\"2019-04-29T20:48:25+00:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Cama\\u00e7ari\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/noticias-em-camacari\\\/#listItem\",\"name\":\"Not\\u00edcias Cama\\u00e7ari\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/noticias-em-camacari\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Cama\\u00e7ari\",\"item\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/noticias-em-camacari\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#listItem\",\"name\":\"Sa\\u00fade em Cama\\u00e7ari: UPA ser\\u00e1 inaugurada em mar\\u00e7o\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#listItem\",\"position\":3,\"name\":\"Sa\\u00fade em Cama\\u00e7ari: UPA ser\\u00e1 inaugurada em mar\\u00e7o\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/noticias-em-camacari\\\/#listItem\",\"name\":\"Not\\u00edcias Cama\\u00e7ari\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Cama\\u00e7ari\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Cama\\u00e7ari e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/author\\\/ecamacari\\\/#author\",\"url\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/author\\\/ecamacari\\\/\",\"name\":\"Encontra Cama\\u00e7ari\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Cama\\u00e7ari\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/\",\"name\":\"Sa\\u00fade em Cama\\u00e7ari: UPA ser\\u00e1 inaugurada em mar\\u00e7o - Encontra Cama\\u00e7ari\",\"description\":\"Durante visita \\u00e0s obras de constru\\u00e7\\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\\u00fade ser\\u00e1 inaugurado no final de mar\\u00e7o. De acordo com o gestor, a expectativa \\u00e9 muito grande para a conclus\\u00e3o das obras. \\u201cEm breve, a popula\\u00e7\\u00e3o j\\u00e1 ter\\u00e1 atendimento na\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/saude-em-camacari-upa-sera-inaugurada-em-marco\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/author\\\/ecamacari\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/author\\\/ecamacari\\\/#author\"},\"datePublished\":\"2014-02-11T13:07:34+00:00\",\"dateModified\":\"2019-04-29T20:48:25+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/\",\"name\":\"Encontra Cama\\u00e7ari\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Cama\\u00e7ari e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontracamacari.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari","description":"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na","canonical_url":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#blogposting","name":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari","headline":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o","author":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/author\/ecamacari\/#author"},"publisher":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/#organization"},"datePublished":"2014-02-11T13:07:34+00:00","dateModified":"2019-04-29T20:48:25+00:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#webpage"},"articleSection":"Not\u00edcias Cama\u00e7ari"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre#listItem","position":1,"name":"Home","item":"https:\/\/www.encontracamacari.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/#listItem","name":"Not\u00edcias Cama\u00e7ari"}},{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/#listItem","position":2,"name":"Not\u00edcias Cama\u00e7ari","item":"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#listItem","name":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#listItem","position":3,"name":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/#listItem","name":"Not\u00edcias Cama\u00e7ari"}}]},{"@type":"Organization","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/#organization","name":"Encontra Cama\u00e7ari","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Cama\u00e7ari e regi\u00e3o.","url":"https:\/\/www.encontracamacari.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/author\/ecamacari\/#author","url":"https:\/\/www.encontracamacari.com.br\/sobre\/author\/ecamacari\/","name":"Encontra Cama\u00e7ari","image":{"@type":"ImageObject","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Cama\u00e7ari"}},{"@type":"WebPage","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#webpage","url":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/","name":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari","description":"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/author\/ecamacari\/#author"},"creator":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/author\/ecamacari\/#author"},"datePublished":"2014-02-11T13:07:34+00:00","dateModified":"2019-04-29T20:48:25+00:00"},{"@type":"WebSite","@id":"https:\/\/www.encontracamacari.com.br\/sobre\/#website","url":"https:\/\/www.encontracamacari.com.br\/sobre\/","name":"Encontra Cama\u00e7ari","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Cama\u00e7ari e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontracamacari.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Cama\u00e7ari - Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Cama\u00e7ari e regi\u00e3o.","og:type":"article","og:title":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari","og:description":"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na","og:url":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/","article:published_time":"2014-02-11T13:07:34+00:00","article:modified_time":"2019-04-29T20:48:25+00:00","twitter:card":"summary_large_image","twitter:title":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o - Encontra Cama\u00e7ari","twitter:description":"Durante visita \u00e0s obras de constru\u00e7\u00e3o da UPA (Unidade de Pronto Atendimento) do bairro Gleba A, o prefeito Ademar Delgado afirmou que o equipamento de sa\u00fade ser\u00e1 inaugurado no final de mar\u00e7o. De acordo com o gestor, a expectativa \u00e9 muito grande para a conclus\u00e3o das obras. \u201cEm breve, a popula\u00e7\u00e3o j\u00e1 ter\u00e1 atendimento na"},"aioseo_meta_data":{"post_id":"65","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2022-09-09 18:46:12","updated":"2026-08-05 23:22:15","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracamacari.com.br\/sobre\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/\" title=\"Not\u00edcias Cama\u00e7ari\">Not\u00edcias Cama\u00e7ari<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.encontracamacari.com.br\/sobre"},{"label":"Not\u00edcias Cama\u00e7ari","link":"https:\/\/www.encontracamacari.com.br\/sobre\/noticias-em-camacari\/"},{"label":"Sa\u00fade em Cama\u00e7ari: UPA ser\u00e1 inaugurada em mar\u00e7o","link":"https:\/\/www.encontracamacari.com.br\/sobre\/saude-em-camacari-upa-sera-inaugurada-em-marco\/"}],"_links":{"self":[{"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":2,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":150,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/posts\/65\/revisions\/150"}],"wp:attachment":[{"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontracamacari.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}